{"id":22850,"date":"2023-02-14T12:00:55","date_gmt":"2023-02-14T12:00:55","guid":{"rendered":"https:\/\/formatgeriaxarcuteriablanca.com\/aviso-legal\/"},"modified":"2023-03-01T13:07:10","modified_gmt":"2023-03-01T13:07:10","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"22850\" class=\"elementor elementor-22850 elementor-22365\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abc5078 sc_layouts_hide_on_wide sc_layouts_hide_on_desktop sc_layouts_hide_on_notebook sc_layouts_hide_on_tablet sc_layouts_hide_on_mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"abc5078\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff585ea sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"ff585ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4426983 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"4426983\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Aviso legal<\/p>\n<h3>El Av\u00eds legal<\/h3>\n<p>nostre Av\u00eds legal<\/p>\n<p>Llelleix el Av\u00eds legal, Av\u00eds legal, Av\u00eds Legal, Av\u00eds legal<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16d8d72 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"16d8d72\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-22509\" alt=\"Av\u00eds legal\" srcset=\"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-150x150.png 150w, https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-300x300.png 300w, https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-370x370.png 370w, https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-120x120.png 120w, https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-410x410.png 410w, https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal.png 512w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-185be34 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"185be34\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-506707a sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"506707a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6abe85 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"e6abe85\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3>I. INFORMACI\u00d3N GENERAL<\/h3>\n<p>En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de <a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2002-13758\" target=\"_blank\" rel=\"noopener\">Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico<\/a> (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n los siguientes datos de informaci\u00f3n general de este sitio web:<\/p>\n<p>La titularidad de este sitio web, <a href=\"https:\/\/www.formatgeriaxarcuteriablanca.com\/\"><span class=\"blanc-space ng-binding\">https:\/\/www.formatgeriaxarcuteriablanca.com\/<\/span><\/a>, (en adelante, Sitio Web) la ostenta: <span class=\"blanc-space ng-binding\">Francesc Pag\u00e8s Massuet<\/span>, con NIF: <span class=\"blanc-space ng-binding\">77531158K<\/span>, y cuyos datos de contacto son:<\/p>\n<p>Direcci\u00f3n: <span class=\"blanc-space ng-binding\">Mercat de la Pla\u00e7a de Cuba, parada 22<\/span><\/p>\n<p>Tel\u00e9fono de contacto:<\/p>\n<p class=\"\" style=\"box-sizing: border-box; font-family: Roboto, sans-serif; --tw-border-spacing-x: 0; --tw-border-spacing-y: 0; --tw-translate-x: 0; --tw-translate-y: 0; --tw-rotate: 0; --tw-skew-x: 0; --tw-skew-y: 0; --tw-scale-x: 1; --tw-scale-y: 1; --tw-scroll-snap-strictness: proximity; --tw-ring-offset-width: 0px; --tw-ring-offset-color: #fff; --tw-ring-color: rgb(59 130 246 \/ 0.5); --tw-ring-offset-shadow: 0 0 #0000; --tw-ring-shadow: 0 0 #0000; --tw-shadow: 0 0 #0000; --tw-shadow-colored: 0 0 #0000; margin-top: 0px; margin-bottom: 1rem; line-height: 1.7rem;\">Fax: <span class=\"blanc-space ng-binding\">626657145<\/span><\/p>\n<p>Email de contacto: <a href=\"mailto:info@formatgeriaxarcuteriablanca.com\"><span class=\"blanc-space ng-binding\">info@formatgeriaxarcuteriablanca.com<\/span><\/a><\/p>\n<h3>II. T\u00c9RMINOS Y CONDICIONES GENERALES DE USO<\/h3>\n<h4>El objeto de las condiciones: El Sitio Web<\/h4>\n<p>El objeto de las presentes Condiciones Generales de Uso (en adelante, Condiciones) es regular el acceso y la utilizaci\u00f3n del Sitio Web. A los efectos de las presentes Condiciones se entender\u00e1 como Sitio Web: la apariencia externa de los interfaces de pantalla, tanto de forma est\u00e1tica como de forma din\u00e1mica, es decir, el \u00e1rbol de navegaci\u00f3n; y todos los elementos integrados tanto en los interfaces de pantalla como en el \u00e1rbol de navegaci\u00f3n (en adelante, Contenidos) y todos aquellos servicios o recursos en l\u00ednea que en su caso ofrezca a los Usuarios (en adelante, Servicios).<\/p>\n<p><span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> se reserva la facultad de modificar, en cualquier momento, y sin aviso previo, la presentaci\u00f3n y configuraci\u00f3n del Sitio Web y de los Contenidos y Servicios que en \u00e9l pudieran estar incorporados. El Usuario reconoce y acepta que en cualquier momento <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> pueda interrumpir, desactivar y\/o cancelar cualquiera de estos elementos que se integran en el Sitio Web o el acceso a los mismos.<\/p>\n<p>El acceso al Sitio Web por el Usuario tiene car\u00e1cter libre y, por regla general, es gratuito sin que el Usuario tenga que proporcionar una contraprestaci\u00f3n para poder disfrutar de ello, salvo en lo relativo al coste de conexi\u00f3n a trav\u00e9s de la red de telecomunicaciones suministrada por el proveedor de acceso que hubiere contratado el Usuario.<\/p>\n<p>La utilizaci\u00f3n de alguno de los Contenidos o Servicios del Sitio Web podr\u00e1 hacerse mediante la suscripci\u00f3n o registro previo del Usuario.<\/p>\n<h4>El Usuario<\/h4>\n<p>El acceso, la navegaci\u00f3n y uso del Sitio Web, as\u00ed como por los espacios habilitados para interactuar entre los Usuarios, y el Usuario y <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span>, como los comentarios y\/o espacios de blogging, confiere la condici\u00f3n de Usuario, por lo que se aceptan, desde que se inicia la navegaci\u00f3n por el Sitio Web, todas las Condiciones aqu\u00ed establecidas, as\u00ed como sus ulteriores modificaciones, sin perjuicio de la aplicaci\u00f3n de la correspondiente normativa legal de obligado cumplimiento seg\u00fan el caso. Dada la relevancia de lo anterior, se recomienda al Usuario leerlas cada vez que visite el Sitio Web.<\/p>\n<p>El Sitio Web de <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> proporciona gran diversidad de informaci\u00f3n, servicios y datos. El Usuario asume su responsabilidad para realizar un uso correcto del Sitio Web. Esta responsabilidad se extender\u00e1 a:<\/p>\n<ul>\n<li>Un uso de la informaci\u00f3n, Contenidos y\/o Servicios y datos ofrecidos por <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> sin que sea contrario a lo dispuesto por las presentes Condiciones, la Ley, la moral o el orden p\u00fablico, o que de cualquier otro modo puedan suponer lesi\u00f3n de los derechos de terceros o del mismo funcionamiento del Sitio Web.<\/li>\n<li>La veracidad y licitud de las informaciones aportadas por el Usuario en los formularios extendidos por <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> para el acceso a ciertos Contenidos o Servicios ofrecidos por el Sitio Web. En todo caso, el Usuario notificar\u00e1 de forma inmediata a <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> acerca de cualquier hecho que permita el uso indebido de la informaci\u00f3n registrada en dichos formularios, tales como, pero no solo, el robo, extrav\u00edo, o el acceso no autorizado a identificadores y\/o contrase\u00f1as, con el fin de proceder a su inmediata cancelaci\u00f3n.<\/li>\n<\/ul>\n<p><span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> se reserva el derecho de retirar todos aquellos comentarios y aportaciones que vulneren la ley, el respeto a la dignidad de la persona, que sean discriminatorios, xen\u00f3fobos, racistas, pornogr\u00e1ficos, spamming, que atenten contra la juventud o la infancia, el orden o la seguridad p\u00fablica o que, a su juicio, no resultaran adecuados para su publicaci\u00f3n.<\/p>\n<p>En cualquier caso, <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> no ser\u00e1 responsable de las opiniones vertidas por los Usuarios a trav\u00e9s de comentarios u otras herramientas de blogging o de participaci\u00f3n que pueda haber.<\/p>\n<p>El mero acceso a este Sitio Web no supone entablar ning\u00fan tipo de relaci\u00f3n de car\u00e1cter comercial entre <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> y el Usuario.<\/p>\n<p>El Usuario declara ser mayor de edad y disponer de la capacidad jur\u00eddica suficiente para vincularse por las presentes Condiciones. Por lo tanto, este Sitio Web de <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> no se dirige a menores de edad. <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> declina cualquier responsabilidad por el incumplimiento de este requisito.<\/p>\n<p>El Sitio Web est\u00e1 dirigido principalmente a Usuarios residentes en . <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> no asegura que el Sitio Web cumpla con legislaciones de otros pa\u00edses, ya sea total o parcialmente. Si el Usuario reside o tiene su domiciliado en otro lugar y decide acceder y\/o navegar en el Sitio Web lo har\u00e1 bajo su propia responsabilidad, deber\u00e1 asegurarse de que tal acceso y navegaci\u00f3n cumple con la legislaci\u00f3n local que le es aplicable, no asumiendo <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> responsabilidad alguna que se pueda derivar de dicho acceso.<\/p>\n<h3>III. ACCESO Y NAVEGACI\u00d3N EN EL SITIO WEB: EXCLUSI\u00d3N DE GARANT\u00cdAS Y RESPONSABILIDAD<\/h3>\n<p><span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> no garantiza la continuidad, disponibilidad y utilidad del Sitio Web, ni de los Contenidos o Servicios. <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> har\u00e1 todo lo posible por el buen funcionamiento del Sitio Web, sin embargo, no se responsabiliza ni garantiza que el acceso a este Sitio Web no vaya a ser ininterrumpido o que est\u00e9 libre de error.<\/p>\n<p>Tampoco se responsabiliza o garantiza que el contenido o software al que pueda accederse a trav\u00e9s de este Sitio Web, est\u00e9 libre de error o cause un da\u00f1o al sistema inform\u00e1tico (software y hardware) del Usuario. En ning\u00fan caso <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> ser\u00e1 responsable por las p\u00e9rdidas, da\u00f1os o perjuicios de cualquier tipo que surjan por el acceso, navegaci\u00f3n y el uso del Sitio Web, incluy\u00e9ndose, pero no limit\u00e1ndose, a los ocasionados a los sistemas inform\u00e1ticos o los provocados por la introducci\u00f3n de virus.<\/p>\n<p><span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> tampoco se hace responsable de los da\u00f1os que pudiesen ocasionarse a los usuarios por un uso inadecuado de este Sitio Web. En particular, no se hace responsable en modo alguno de las ca\u00eddas, interrupciones, falta o defecto de las telecomunicaciones que pudieran ocurrir.<\/p>\n<h3>IV. POL\u00cdTICA DE ENLACES<\/h3>\n<p>Se informa que el Sitio Web de <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> pone o puede poner a disposici\u00f3n de los Usuarios medios de enlace (como, entre otros, links, banners, botones), directorios y motores de b\u00fasqueda que permiten a los Usuarios acceder a sitios web pertenecientes y\/o gestionados por terceros.<\/p>\n<p>La instalaci\u00f3n de estos enlaces, directorios y motores de b\u00fasqueda en el Sitio Web tiene por objeto facilitar a los Usuarios la b\u00fasqueda de y acceso a la informaci\u00f3n disponible en Internet, sin que pueda considerarse una sugerencia, recomendaci\u00f3n o invitaci\u00f3n para la visita de los mismos.<\/p>\n<p><span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> no ofrece ni comercializa por s\u00ed ni por medio de terceros los productos y\/o servicios disponibles en dichos sitios enlazados.<\/p>\n<p>Asimismo, tampoco garantizar\u00e1 la disponibilidad t\u00e9cnica, exactitud, veracidad, validez o legalidad de sitios ajenos a su propiedad a los que se pueda acceder por medio de los enlaces.<\/p>\n<p><span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> en ning\u00fan caso revisar\u00e1 o controlar\u00e1 el contenido de otros sitios web, as\u00ed como tampoco aprueba, examina ni hace propios los productos y servicios, contenidos, archivos y cualquier otro material existente en los referidos sitios enlazados.<\/p>\n<p><span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> no asume ninguna responsabilidad por los da\u00f1os y perjuicios que pudieran producirse por el acceso, uso, calidad o licitud de los contenidos, comunicaciones, opiniones, productos y servicios de los sitios web no gestionados por <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> y que sean enlazados en este Sitio Web.<\/p>\n<p>El Usuario o tercero que realice un hiperv\u00ednculo desde una p\u00e1gina web de otro, distinto, sitio web al Sitio Web de <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> deber\u00e1 saber que:<\/p>\n<p>No se permite la reproducci\u00f3n \u2014total o parcialmente\u2014 de ninguno de los Contenidos y\/o Servicios del Sitio Web sin autorizaci\u00f3n expresa de <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span>.<\/p>\n<p>No se permite tampoco ninguna manifestaci\u00f3n falsa, inexacta o incorrecta sobre el Sitio Web de <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span>, ni sobre los Contenidos y\/o Servicios del mismo.<\/p>\n<p>A excepci\u00f3n del hiperv\u00ednculo, el sitio web en el que se establezca dicho hiperenlace no contendr\u00e1 ning\u00fan elemento, de este Sitio Web, protegido como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, salvo autorizaci\u00f3n expresa de <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span>.<\/p>\n<p>El establecimiento del hiperv\u00ednculo no implicar\u00e1 la existencia de relaciones entre <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> y el titular del sitio web desde el cual se realice, ni el conocimiento y aceptaci\u00f3n de <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> de los contenidos, servicios y\/o actividades ofrecidas en dicho sitio web, y viceversa.<\/p>\n<h3>V. PROPIEDAD INTELECTUAL E INDUSTRIAL<\/h3>\n<p><span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> por s\u00ed o como parte cesionaria, es titular de todos los derechos de propiedad intelectual e industrial del Sitio Web, as\u00ed como de los elementos contenidos en el mismo (a t\u00edtulo enunciativo y no exhaustivo, im\u00e1genes, sonido, audio, v\u00eddeo, software o textos, marcas o logotipos, combinaciones de colores, estructura y dise\u00f1o, selecci\u00f3n de materiales usados, programas de ordenador necesarios para su funcionamiento, acceso y uso, etc.). Ser\u00e1n, por consiguiente, obras protegidas como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, si\u00e9ndoles aplicables tanto la normativa espa\u00f1ola y comunitaria en este campo, como los tratados internacionales relativos a la materia y suscritos por Espa\u00f1a.<\/p>\n<p>Todos los derechos reservados. En virtud de lo dispuesto en la Ley de Propiedad Intelectual, quedan expresamente prohibidas la reproducci\u00f3n, la distribuci\u00f3n y la comunicaci\u00f3n p\u00fablica, incluida su modalidad de puesta a disposici\u00f3n, de la totalidad o parte de los contenidos de esta p\u00e1gina web, con fines comerciales, en cualquier soporte y por cualquier medio t\u00e9cnico, sin la autorizaci\u00f3n de <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span>.<\/p>\n<p>El Usuario se compromete a respetar los derechos de propiedad intelectual e industrial de <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span>. Podr\u00e1 visualizar los elementos del Sitio Web o incluso imprimirlos, copiarlos y almacenarlos en el disco duro de su ordenador o en cualquier otro soporte f\u00edsico siempre y cuando sea, exclusivamente, para su uso personal. El Usuario, sin embargo, no podr\u00e1 suprimir, alterar, o manipular cualquier dispositivo de protecci\u00f3n o sistema de seguridad que estuviera instalado en el Sitio Web.<\/p>\n<p>En caso de que el Usuario o tercero considere que cualquiera de los Contenidos del Sitio Web suponga una violaci\u00f3n de los derechos de protecci\u00f3n de la propiedad intelectual, deber\u00e1 comunicarlo inmediatamente a <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> a trav\u00e9s de los datos de contacto del apartado de INFORMACI\u00d3N GENERAL de este Aviso Legal y Condiciones Generales de Uso.<\/p>\n<h3>VI. ACCIONES LEGALES, LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<\/h3>\n<p><span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> se reserva la facultad de presentar las acciones civiles o penales que considere necesarias por la utilizaci\u00f3n indebida del Sitio Web y Contenidos, o por el incumplimiento de las presentes Condiciones.<\/p>\n<p>La relaci\u00f3n entre el Usuario y <span class=\"blanc-space ng-binding\">Formatgeria Xarcuteria Blanca<\/span> se regir\u00e1 por la normativa vigente y de aplicaci\u00f3n en el territorio espa\u00f1ol. De surgir cualquier controversia en relaci\u00f3n con la interpretaci\u00f3n y\/o a la aplicaci\u00f3n de estas Condiciones las partes someter\u00e1n sus conflictos a la jurisdicci\u00f3n ordinaria someti\u00e9ndose a los jueces y tribunales que correspondan conforme a derecho.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aviso legal El Av\u00eds legal nostre Av\u00eds legal Llelleix el Av\u00eds legal, Av\u00eds legal, Av\u00eds Legal, Av\u00eds legal I. INFORMACI\u00d3N GENERAL En cumplimiento con el deber de informaci\u00f3n dispuesto en&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22850","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aviso legal - Formatgeria Xarcuteria Blanca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso legal - Formatgeria Xarcuteria Blanca\" \/>\n<meta property=\"og:description\" content=\"Aviso legal El Av\u00eds legal nostre Av\u00eds legal Llelleix el Av\u00eds legal, Av\u00eds legal, Av\u00eds Legal, Av\u00eds legal I. INFORMACI\u00d3N GENERAL En cumplimiento con el deber de informaci\u00f3n dispuesto en&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Formatgeria Xarcuteria Blanca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/formatgeriablanca.formatgeriaxarcuteria\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-01T13:07:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-150x150.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@formatge_blanca\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/\",\"url\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/\",\"name\":\"Aviso legal - Formatgeria Xarcuteria Blanca\",\"isPartOf\":{\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-150x150.png\",\"datePublished\":\"2023-02-14T12:00:55+00:00\",\"dateModified\":\"2023-03-01T13:07:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/#primaryimage\",\"url\":\"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-150x150.png\",\"contentUrl\":\"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-150x150.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/formatgeria-xarcuteria-blanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#website\",\"url\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/\",\"name\":\"Formatgeria Xarcuteria Blanca\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#organization\",\"name\":\"Formatgeria Xarcuteria Blanca\",\"url\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/logo.jpg\",\"contentUrl\":\"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/logo.jpg\",\"width\":200,\"height\":103,\"caption\":\"Formatgeria Xarcuteria Blanca\"},\"image\":{\"@id\":\"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/es-es.facebook.com\/formatgeriablanca.formatgeriaxarcuteria\",\"https:\/\/x.com\/formatge_blanca\",\"https:\/\/www.instagram.com\/formatgeria_blanca\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso legal - Formatgeria Xarcuteria Blanca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/","og_locale":"es_ES","og_type":"article","og_title":"Aviso legal - Formatgeria Xarcuteria Blanca","og_description":"Aviso legal El Av\u00eds legal nostre Av\u00eds legal Llelleix el Av\u00eds legal, Av\u00eds legal, Av\u00eds Legal, Av\u00eds legal I. INFORMACI\u00d3N GENERAL En cumplimiento con el deber de informaci\u00f3n dispuesto en&hellip;","og_url":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/","og_site_name":"Formatgeria Xarcuteria Blanca","article_publisher":"https:\/\/es-es.facebook.com\/formatgeriablanca.formatgeriaxarcuteria","article_modified_time":"2023-03-01T13:07:10+00:00","og_image":[{"url":"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-150x150.png"}],"twitter_card":"summary_large_image","twitter_site":"@formatge_blanca","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/","url":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/","name":"Aviso legal - Formatgeria Xarcuteria Blanca","isPartOf":{"@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/#primaryimage"},"image":{"@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/#primaryimage"},"thumbnailUrl":"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-150x150.png","datePublished":"2023-02-14T12:00:55+00:00","dateModified":"2023-03-01T13:07:10+00:00","breadcrumb":{"@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/#primaryimage","url":"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-150x150.png","contentUrl":"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/legal-150x150.png"},{"@type":"BreadcrumbList","@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/formatgeria-xarcuteria-blanca\/"},{"@type":"ListItem","position":2,"name":"Aviso legal"}]},{"@type":"WebSite","@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#website","url":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/","name":"Formatgeria Xarcuteria Blanca","description":"","publisher":{"@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#organization","name":"Formatgeria Xarcuteria Blanca","url":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/logo.jpg","contentUrl":"https:\/\/formatgeriaxarcuteriablanca.com\/wp-content\/uploads\/2023\/02\/logo.jpg","width":200,"height":103,"caption":"Formatgeria Xarcuteria Blanca"},"image":{"@id":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/formatgeriablanca.formatgeriaxarcuteria","https:\/\/x.com\/formatge_blanca","https:\/\/www.instagram.com\/formatgeria_blanca\/"]}]}},"_links":{"self":[{"href":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/wp-json\/wp\/v2\/pages\/22850"}],"collection":[{"href":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/wp-json\/wp\/v2\/comments?post=22850"}],"version-history":[{"count":1,"href":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/wp-json\/wp\/v2\/pages\/22850\/revisions"}],"predecessor-version":[{"id":22851,"href":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/wp-json\/wp\/v2\/pages\/22850\/revisions\/22851"}],"wp:attachment":[{"href":"https:\/\/formatgeriaxarcuteriablanca.com\/es\/wp-json\/wp\/v2\/media?parent=22850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}